{"id":48,"count":0,"description":"","link":"https:\/\/hds-p.org\/a\/category\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\/","name":"\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631","slug":"%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1","taxonomy":"category","parent":36,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hds-p.org\/a\/category\/\u0645\u064a\u062f\u064a\u0627\/\u0625\u0639\u0627\u062f\u0629-\u0646\u0634\u0631\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hds-p.org\/a\/category\/\u0645\u064a\u062f\u064a\u0627\/\u0625\u0639\u0627\u062f\u0629-\u0646\u0634\u0631\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hds-p.org\\\/a\\\/category\\\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\\\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\\\/\",\"url\":\"https:\\\/\\\/hds-p.org\\\/a\\\/category\\\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\\\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\\\/\",\"name\":\"\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hds-p.org\\\/a\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hds-p.org\\\/a\\\/category\\\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\\\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hds-p.org\\\/a\\\/category\\\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\\\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/hds-p.org\\\/a\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0645\u064a\u062f\u064a\u0627\",\"item\":\"https:\\\/\\\/hds-p.org\\\/a\\\/category\\\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hds-p.org\\\/a\\\/#website\",\"url\":\"https:\\\/\\\/hds-p.org\\\/a\\\/\",\"name\":\"\u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a\",\"description\":\"\u0627\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hds-p.org\\\/a\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hds-p.org\/a\/category\/\u0645\u064a\u062f\u064a\u0627\/\u0625\u0639\u0627\u062f\u0629-\u0646\u0634\u0631\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a","og_url":"https:\/\/hds-p.org\/a\/category\/\u0645\u064a\u062f\u064a\u0627\/\u0625\u0639\u0627\u062f\u0629-\u0646\u0634\u0631\/","og_site_name":"\u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hds-p.org\/a\/category\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\/","url":"https:\/\/hds-p.org\/a\/category\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\/","name":"\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a","isPartOf":{"@id":"https:\/\/hds-p.org\/a\/#website"},"breadcrumb":{"@id":"https:\/\/hds-p.org\/a\/category\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/hds-p.org\/a\/category\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\/%d8%a5%d8%b9%d8%a7%d8%af%d8%a9-%d9%86%d8%b4%d8%b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/hds-p.org\/a\/"},{"@type":"ListItem","position":2,"name":"\u0645\u064a\u062f\u064a\u0627","item":"https:\/\/hds-p.org\/a\/category\/%d9%85%d9%8a%d8%af%d9%8a%d8%a7\/"},{"@type":"ListItem","position":3,"name":"\u0625\u0639\u0627\u062f\u0629 \u0646\u0634\u0631"}]},{"@type":"WebSite","@id":"https:\/\/hds-p.org\/a\/#website","url":"https:\/\/hds-p.org\/a\/","name":"\u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a","description":"\u0627\u0644\u062d\u0632\u0628 \u0627\u0644\u062f\u0633\u062a\u0648\u0631\u064a \u0627\u0644\u0633\u0648\u0631\u064a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hds-p.org\/a\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/hds-p.org\/a\/wp-json\/wp\/v2\/categories\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hds-p.org\/a\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hds-p.org\/a\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/hds-p.org\/a\/wp-json\/wp\/v2\/categories\/36"}],"wp:post_type":[{"href":"https:\/\/hds-p.org\/a\/wp-json\/wp\/v2\/posts?categories=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}